{"id":11674,"date":"2024-08-30T16:10:12","date_gmt":"2024-08-30T14:10:12","guid":{"rendered":"https:\/\/www.gba-polska.pl\/?page_id=11674"},"modified":"2024-09-03T16:01:35","modified_gmt":"2024-09-03T14:01:35","slug":"seals-of-quality-dietary-supplements","status":"publish","type":"page","link":"https:\/\/www.gba-polska.pl\/en\/seals-of-quality-dietary-supplements\/","title":{"rendered":"Seals of Quality"},"content":{"rendered":"<p><section id=\"bt_bb_section6a04d66768a8d\" class=\"bt_bb_section bt_bb_color_scheme_11 bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_background_overlay_dark_solid bt_bb_top_spacing_extra_large bt_bb_bottom_spacing_large bt-dark-skin\" style=\"; --section-primary-color:#ffffff; --section-secondary-color:#181818;\" data-bt-override-class=\"null\"><div class=\"bt_bb_background_image_holder_wrapper\"><div class=\"bt_bb_background_image_holder btLazyLoadBackground\"  data-background_image_src=\"https:\/\/www.gba-polska.pl\/wp-content\/uploads\/2024\/08\/GBA-POLSKA-suplementy-diety.jpg\" data-parallax-zoom-start=\"1\" data-parallax-zoom-end=\"1\" data-parallax-blur-start=\"0\" data-parallax-blur-end=\"0\" data-parallax-opacity-start=\"1\" data-parallax-opacity-end=\"1\" style=\" background-image: url(&#039;https:\/\/www.gba-polska.pl\/wp-content\/plugins\/bold-page-builder\/img\/blank.gif&#039;);\"><\/div><\/div><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-6 col-xl-6 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal bt_bb_animation_fade_in zoom_out animate\" style=\"; --column-width:6;\" data-width=\"6\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><header class=\"bt_bb_headline bt_bb_dash_top bt_bb_superheadline bt_bb_size_large bt_bb_align_inherit\" data-bt-override-class=\"null\"><h1><span class=\"bt_bb_headline_superheadline\"><span>Dietary Supplements<\/span><\/span><span class=\"bt_bb_headline_content\"><span>Seal of Quality<\/span><\/span><\/h1><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_60\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><div  class=\"bt_bb_column col-xxl-6 col-xl-6 bt_bb_vertical_align_top bt_bb_align_right bt_bb_padding_40 bt_bb_animation_fade_in zoom_out animate\" style=\"; --column-width:6;\" data-width=\"6\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_right&quot;,&quot;def&quot;:&quot;right&quot;,&quot;xl&quot;:&quot;right&quot;}}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a04d66769466\" class=\"bt_bb_section bt_bb_color_scheme_2 bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_top_spacing_40 bt_bb_bottom_spacing_40\" style=\"z-index: 1;; --section-primary-color:#000000; --section-secondary-color:#ffffff;\" data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_40 bt_bb_animation_fade_in zoom_out animate\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_left&quot;,&quot;def&quot;:&quot;left&quot;,&quot;xl&quot;:&quot;left&quot;}}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_inherit bt_bb_align_inherit\" data-bt-override-class=\"null\"><h4><span class=\"bt_bb_headline_content\"><span>The GBA POLSKA quality seal is a guarantee of the highest product quality and a solid basis for building a competitive advantage in the local and global market.<\/p><br \/>\n<p>The quality seal confirms that the product has been tested in the laboratories of GBA POLSKA.<\/span><\/span><\/h4><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<p>Receiving the GBA POLSKA Quality Seal means that a product meets the highest safety standards. For manufacturers, the Quality Seal is proof that their products are trustworthy and recommendable. For consumers, it is the assurance that they are choosing a product that has been thoroughly tested and verified by independent specialists.<\/p>\n<p>The GBA POLSKA Quality Seal means that each batch of the product has been tested in an independent GBA POLSKA laboratory. The GBA POLSKA Quality Seal can be a key element in the choice of a product by conscious consumers.<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a04d66769db1\" class=\"bt_bb_section bt_bb_color_scheme_2 bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_top_spacing_40 bt_bb_bottom_spacing_40\" style=\"z-index: 1;; --section-primary-color:#000000; --section-secondary-color:#ffffff;\" data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal bt_bb_animation_fade_in zoom_out animate\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_tabs bt_bb_color_scheme_13 bt_bb_style_simple bt_bb_shape_square\" style=\"; --tabs-primary-color:#000; --tabs-secondary-color:#fff;\" data-bt-override-class=\"{}\"><ul class=\"bt_bb_tabs_header\"><li><span>PREMIUM SAFETY<\/span><\/li><\/ul><div class=\"bt_bb_tabs_tabs\"><div class=\"bt_bb_tab_item has_bt_bb_image\">\n\t\t\t<div class=\"bt_bb_tab_content\"><div class=\" bt_bb_row_inner\"   data-bt-override-class=\"{}\"><div class=\"bt_bb_row_inner_holder\"  ><div  class=\"bt_bb_column_inner col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\"  data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_inner_content\"><div class=\"bt_bb_column_inner_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_image bt_bb_shape_square bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle bt_bb_remove_padding_yes bt_bb_fill_background_color_full\" data-bt-override-class=\"null\"><span><img src = \"https:\/\/www.gba-polska.pl\/wp-content\/plugins\/bold-page-builder\/img\/blank.gif\" data-full_image_src=\"https:\/\/www.gba-polska.pl\/wp-content\/uploads\/2024\/08\/GBA-POLSKA-premium-safety-suplementy-diety.jpg\" data-image_src=\"https:\/\/www.gba-polska.pl\/wp-content\/uploads\/2024\/08\/GBA-POLSKA-premium-safety-suplementy-diety.jpg\" title=\"GBA-POLSKA-premium-safety-suplementy-diety\" alt=\"https:\/\/www.gba-polska.pl\/wp-content\/uploads\/2024\/08\/GBA-POLSKA-premium-safety-suplementy-diety.jpg\" class=\"btLazyLoadImage\"><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<p><strong>PREMIUM SAFETY<br \/>\n<\/strong><\/p>\n<p>Laboratory Proofed Quality<\/p>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_10\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_accordion bt_bb_color_scheme_5 bt_bb_style_simple bt_bb_shape_square\" style=\"; --accordion-primary-color:#000000; --accordion-secondary-color:#004787;\"><div class=\"bt_bb_accordion_item\"><div class=\"bt_bb_accordion_item_title\">Description<\/div><div class=\"bt_bb_accordion_item_content\"><div  class=\"bt_bb_text\" ><\/p>\n<p>The Premium Safety seal for a dietary supplement is a guarantee of the safety of each product batch, confirmed by an independent GBA POLSKA laboratory. As part of this procedure, detailed tests are carried out, the scope of which is determined by experts based on the composition of a given supplement. The safety of the product is assessed on the basis of the results of analyses of the level of impurities, which must fall within the applicable limits. In addition, production standards are verified through an audit conducted at the production facility.<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a04d6676c713\" class=\"bt_bb_section bt_bb_color_scheme_2 bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_top_spacing_40 bt_bb_bottom_spacing_40\" style=\"z-index: 1;; --section-primary-color:#000000; --section-secondary-color:#ffffff;\" data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_40 bt_bb_animation_fade_in zoom_out animate\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_left&quot;,&quot;def&quot;:&quot;left&quot;,&quot;xl&quot;:&quot;left&quot;}}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_inherit bt_bb_align_inherit\" data-bt-override-class=\"null\"><h4><span class=\"bt_bb_headline_content\"><span>4 steps to obtain the GBA POLSKA Quality Seal<\/span><\/span><\/h4><\/header><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a04d6676ce15\" class=\"bt_bb_section bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_top_spacing_40 bt_bb_bottom_spacing_40\"  data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal bt_bb_animation_fade_in zoom_out animate\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_left&quot;,&quot;def&quot;:&quot;left&quot;,&quot;xl&quot;:&quot;left&quot;}}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_tabs bt_bb_color_scheme_13 bt_bb_style_simple bt_bb_shape_square\" style=\"; --tabs-primary-color:#000; --tabs-secondary-color:#fff;\" data-bt-override-class=\"{}\"><ul class=\"bt_bb_tabs_header\"><li><span>1. APPLICATION FOR A SEAL<\/span><\/li><li><span>2. VERIFICATION<\/span><\/li><li><span>3. CONDUCT OF TESTS AND EVALUATION OF RESULTS<\/span><\/li><li><span>4. AWARD OF THE QUALITY SEAL<\/span><\/li><\/ul><div class=\"bt_bb_tabs_tabs\"><div class=\"bt_bb_tab_item has_bt_bb_image\">\n\t\t\t<div class=\"bt_bb_tab_content\"><div class=\" bt_bb_row_inner\"   data-bt-override-class=\"{}\"><div class=\"bt_bb_row_inner_holder\"  ><div  class=\"bt_bb_column_inner col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\"  data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_inner_content\"><div class=\"bt_bb_column_inner_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_image bt_bb_shape_square bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle bt_bb_remove_padding_yes bt_bb_fill_background_color_full\" data-bt-override-class=\"null\"><span><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_10\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_accordion bt_bb_color_scheme_5 bt_bb_style_simple bt_bb_shape_square\" style=\"; --accordion-primary-color:#000000; --accordion-secondary-color:#004787;\"><div class=\"bt_bb_accordion_item\"><div class=\"bt_bb_accordion_item_title\">STEP 1<\/div><div class=\"bt_bb_accordion_item_content\"><div  class=\"bt_bb_text\" ><\/p>\n<p>Our team will work with you to we will plan the required studies and define their criteria.<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div><div class=\"bt_bb_tab_item has_bt_bb_image\">\n\t\t\t<div class=\"bt_bb_tab_content\"><div class=\" bt_bb_row_inner\"   data-bt-override-class=\"{}\"><div class=\"bt_bb_row_inner_holder\"  ><div  class=\"bt_bb_column_inner col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\"  data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_inner_content\"><div class=\"bt_bb_column_inner_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_image bt_bb_shape_square bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle bt_bb_remove_padding_yes bt_bb_fill_background_color_full\" data-bt-override-class=\"null\"><span><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_10\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_accordion bt_bb_color_scheme_5 bt_bb_style_simple bt_bb_shape_square\" style=\"; --accordion-primary-color:#000000; --accordion-secondary-color:#004787;\"><div class=\"bt_bb_accordion_item\"><div class=\"bt_bb_accordion_item_title\">STEP 2<\/div><div class=\"bt_bb_accordion_item_content\"><div  class=\"bt_bb_text\" ><\/p>\n<p>Verification of manufacturer&#8217;s compliance with quality standards in the manufacturing area.<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div><div class=\"bt_bb_tab_item has_bt_bb_image\">\n\t\t\t<div class=\"bt_bb_tab_content\"><div class=\" bt_bb_row_inner\"   data-bt-override-class=\"{}\"><div class=\"bt_bb_row_inner_holder\"  ><div  class=\"bt_bb_column_inner col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\"  data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_inner_content\"><div class=\"bt_bb_column_inner_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_image bt_bb_shape_square bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle bt_bb_remove_padding_yes bt_bb_fill_background_color_full\" data-bt-override-class=\"null\"><span><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_10\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_accordion bt_bb_color_scheme_5 bt_bb_style_simple bt_bb_shape_square\" style=\"; --accordion-primary-color:#000000; --accordion-secondary-color:#004787;\"><div class=\"bt_bb_accordion_item\"><div class=\"bt_bb_accordion_item_title\">STEP 3<\/div><div class=\"bt_bb_accordion_item_content\"><div  class=\"bt_bb_text\" ><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div><div class=\"bt_bb_tab_item has_bt_bb_image\">\n\t\t\t<div class=\"bt_bb_tab_content\"><div class=\" bt_bb_row_inner\"   data-bt-override-class=\"{}\"><div class=\"bt_bb_row_inner_holder\"  ><div  class=\"bt_bb_column_inner col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\"  data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_inner_content\"><div class=\"bt_bb_column_inner_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_image bt_bb_shape_square bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle bt_bb_remove_padding_yes bt_bb_fill_background_color_full\" data-bt-override-class=\"null\"><span><\/span><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_30\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_10\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_accordion bt_bb_color_scheme_5 bt_bb_style_simple bt_bb_shape_square\" style=\"; --accordion-primary-color:#000000; --accordion-secondary-color:#004787;\"><div class=\"bt_bb_accordion_item\"><div class=\"bt_bb_accordion_item_title\">STEP 4<\/div><div class=\"bt_bb_accordion_item_content\"><div  class=\"bt_bb_text\" ><\/p>\n<p>If your product passes the test stage we will send you a test report and approval to use the Seal of Quality.<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a04d66770afc\" class=\"bt_bb_section bt_bb_color_scheme_2 bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_top_spacing_40 bt_bb_bottom_spacing_40\" style=\"; --section-primary-color:#000000; --section-secondary-color:#ffffff;\" data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_40 bt_bb_animation_fade_in zoom_out animate\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_left&quot;,&quot;def&quot;:&quot;left&quot;,&quot;xl&quot;:&quot;left&quot;}}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_inherit bt_bb_align_inherit\" data-bt-override-class=\"null\"><h4><span class=\"bt_bb_headline_content\"><span>If you want to learn more about the GBA POLSKA Quality Seal and how it is awarded, we encourage you to contact our specialists directly.<\/span><\/span><\/h4><\/header><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><section id=\"bt_bb_section6a04d6677115f\" class=\"bt_bb_section bt_bb_color_scheme_2 bt_bb_layout_boxed_1200 bt_bb_vertical_align_top bt_bb_top_spacing_40 bt_bb_bottom_spacing_40 bt_bb_animation_fade_in zoom_out animate\" style=\"; --section-primary-color:#000000; --section-secondary-color:#ffffff;\" data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 col-xs-12 col-sm-12 col-md-12 col-lg-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_40\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{&quot;bt_bb_align_&quot;:{&quot;current_class&quot;:&quot;bt_bb_align_left&quot;,&quot;def&quot;:&quot;left&quot;,&quot;xl&quot;:&quot;left&quot;}}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_inherit bt_bb_align_inherit\" data-bt-override-class=\"null\"><h3><span class=\"bt_bb_headline_content\"><span>Contact form<\/span><\/span><\/h3><\/header><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_20\" data-bt-override-class=\"null\"><\/div><div  class=\"bt_bb_text\" ><\/p>\n<p><em>Fields marked with squares are mandatory.<\/em><\/p>\n<p>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_20\" data-bt-override-class=\"null\"><\/div><div class=\"bt_bb_contact_form_7\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f11689-o1\" lang=\"pl-PL\" dir=\"ltr\" data-wpcf7-id=\"11689\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/11674#wpcf7-f11689-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formularz kontaktowy\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"11689\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"pl_PL\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f11689-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"bt_bb_cf7_form\">\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element bt_bb_cf7_element_required\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Full name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element bt_bb_cf7_element_required\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company name\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element bt_bb_cf7_element_required\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"country\"><option value=\"Select your country\">Select your country<\/option><option value=\"Australia\">Australia<\/option><option value=\"Austria\">Austria<\/option><option value=\"Belgium\">Belgium<\/option><option value=\"Croatia\">Croatia<\/option><option value=\"Cyprus\">Cyprus<\/option><option value=\"Czech Republic\">Czech Republic<\/option><option value=\"Denmark\">Denmark<\/option><option value=\"Estonia\">Estonia<\/option><option value=\"Finland\">Finland<\/option><option value=\"France\">France<\/option><option value=\"Germany\">Germany<\/option><option value=\"Greece\">Greece<\/option><option value=\"Hungary\">Hungary<\/option><option value=\"India\">India<\/option><option value=\"Ireland\">Ireland<\/option><option value=\"Israel\">Israel<\/option><option value=\"Italy\">Italy<\/option><option value=\"Latvia\">Latvia<\/option><option value=\"Lithuania\">Lithuania<\/option><option value=\"Netherlands\">Netherlands<\/option><option value=\"New Zealand\">New Zealand<\/option><option value=\"Norway\">Norway<\/option><option value=\"Portugal\">Portugal<\/option><option value=\"Romania\">Romania<\/option><option value=\"Serbia\">Serbia<\/option><option value=\"Slovakia\">Slovakia<\/option><option value=\"Slovenia\">Slovenia<\/option><option value=\"Spain\">Spain<\/option><option value=\"Sweden\">Sweden<\/option><option value=\"Switzerland\">Switzerland<\/option><option value=\"Turkey\">Turkey<\/option><option value=\"Ukraine\">Ukraine<\/option><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"Other\">Other<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element bt_bb_cf7_element_required\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-tel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone\" value=\"\" type=\"tel\" name=\"your-tel\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element bt_bb_cf7_element_required\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Company e-mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element bt_bb_cf7_element_required\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"4\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"How can we help?\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element bt_bb_cf7_element_required\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-808\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-808\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I agree to GBA POLSKA processing my personal data for the purposes of my enquiry contained in the form, in accordance with the terms set out in GBA POLSKA's Privacy Policy.<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_row\">\n\t\t<div class=\"bt_bb_cf7_element\">\n\t\t\t<h6>Newsletter GBA POLSKA\n\t\t\t<\/h6>\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-95\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-95\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">I agree to receive commercial information from GBA POLSKA in the form of a newsletter with industry news at the above-mentioned e-mail address and to have my personal data processed for this purpose.<\/span><\/label><\/span><\/span><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"bt_bb_cf7_button bt_bb_cf7_button_larger\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"229\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_bottom_spacing_40\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appropriately empower dynamic leadership skills after business portals. Globally myocardinate interactive supply chains with distinctive quality vectors. Globally revolutionize global sources through interoperable services.<\/p>\n","protected":false},"author":4,"featured_media":3356,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-11674","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/pages\/11674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/comments?post=11674"}],"version-history":[{"count":3,"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/pages\/11674\/revisions"}],"predecessor-version":[{"id":11692,"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/pages\/11674\/revisions\/11692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/media\/3356"}],"wp:attachment":[{"href":"https:\/\/www.gba-polska.pl\/en\/wp-json\/wp\/v2\/media?parent=11674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}